{"id":216,"count":9,"description":"","link":"https:\/\/update.midlandps.org\/index.php\/tag\/sean-zanyk-mclean\/","name":"Sean Zanyk Mclean","slug":"sean-zanyk-mclean","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sean Zanyk Mclean Archives - UPDATE ONLINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/update.midlandps.org\/index.php\/tag\/sean-zanyk-mclean\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sean Zanyk Mclean Archives - UPDATE ONLINE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/update.midlandps.org\/index.php\/tag\/sean-zanyk-mclean\/\" \/>\n<meta property=\"og:site_name\" content=\"UPDATE ONLINE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DowHighUpdate\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/update.midlandps.org\\\/index.php\\\/tag\\\/sean-zanyk-mclean\\\/\",\"url\":\"https:\\\/\\\/update.midlandps.org\\\/index.php\\\/tag\\\/sean-zanyk-mclean\\\/\",\"name\":\"Sean Zanyk Mclean Archives - UPDATE ONLINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/update.midlandps.org\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/update.midlandps.org\\\/#website\",\"url\":\"https:\\\/\\\/update.midlandps.org\\\/\",\"name\":\"UPDATE ONLINE\",\"description\":\"H.H. Dow High School&#039;s award winning news source\",\"publisher\":{\"@id\":\"https:\\\/\\\/update.midlandps.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/update.midlandps.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/update.midlandps.org\\\/#organization\",\"name\":\"Update Online\",\"url\":\"https:\\\/\\\/update.midlandps.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/update.midlandps.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/update.midlandps.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Wordpress-icon.png\",\"contentUrl\":\"https:\\\/\\\/update.midlandps.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Wordpress-icon.png\",\"width\":256,\"height\":256,\"caption\":\"Update Online\"},\"image\":{\"@id\":\"https:\\\/\\\/update.midlandps.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DHSUpdate\\\/\",\"https:\\\/\\\/x.com\\\/DowHighUpdate\",\"https:\\\/\\\/www.instagram.com\\\/dowhighupdate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sean Zanyk Mclean Archives - UPDATE ONLINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/update.midlandps.org\/index.php\/tag\/sean-zanyk-mclean\/","og_locale":"en_US","og_type":"article","og_title":"Sean Zanyk Mclean Archives - UPDATE ONLINE","og_url":"https:\/\/update.midlandps.org\/index.php\/tag\/sean-zanyk-mclean\/","og_site_name":"UPDATE ONLINE","twitter_card":"summary_large_image","twitter_site":"@DowHighUpdate","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/update.midlandps.org\/index.php\/tag\/sean-zanyk-mclean\/","url":"https:\/\/update.midlandps.org\/index.php\/tag\/sean-zanyk-mclean\/","name":"Sean Zanyk Mclean Archives - UPDATE ONLINE","isPartOf":{"@id":"https:\/\/update.midlandps.org\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/update.midlandps.org\/#website","url":"https:\/\/update.midlandps.org\/","name":"UPDATE ONLINE","description":"H.H. Dow High School&#039;s award winning news source","publisher":{"@id":"https:\/\/update.midlandps.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/update.midlandps.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/update.midlandps.org\/#organization","name":"Update Online","url":"https:\/\/update.midlandps.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/update.midlandps.org\/#\/schema\/logo\/image\/","url":"https:\/\/update.midlandps.org\/wp-content\/uploads\/2020\/09\/Wordpress-icon.png","contentUrl":"https:\/\/update.midlandps.org\/wp-content\/uploads\/2020\/09\/Wordpress-icon.png","width":256,"height":256,"caption":"Update Online"},"image":{"@id":"https:\/\/update.midlandps.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DHSUpdate\/","https:\/\/x.com\/DowHighUpdate","https:\/\/www.instagram.com\/dowhighupdate\/"]}]}},"_links":{"self":[{"href":"https:\/\/update.midlandps.org\/index.php\/wp-json\/wp\/v2\/tags\/216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/update.midlandps.org\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/update.midlandps.org\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/update.midlandps.org\/index.php\/wp-json\/wp\/v2\/posts?tags=216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}